{"id":463,"date":"2021-08-03T21:09:24","date_gmt":"2021-08-03T21:09:24","guid":{"rendered":"https:\/\/barrososemminas.org\/2021\/?page_id=463"},"modified":"2021-08-03T22:15:07","modified_gmt":"2021-08-03T22:15:07","slug":"agenda-fr","status":"publish","type":"page","link":"https:\/\/barrososemminas.org\/2021\/fr\/acampada\/agenda-fr\/","title":{"rendered":"Agenda Fran\u00e7ais"},"content":{"rendered":"<div id=\"wppb-builder-container\" class=\"wppb-builder-container\">                <div  class=\"wppb-row-parent  wppb-row-1626951707404 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626951707403  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1628024145459'  data-addon-id='1628024145459'><div class='wppb-addon'><div class=\"wppb-raw-html-addon\"><div class=\"wppb-raw-html-content\"><div class=\"lang_manifest\">\n<p>\n<a href=\"https:\/\/barrososemminas.org\/2021\/acampada\/agenda\/\">Portugu\u00eas\/Galego<\/a> \n<a href=\"https:\/\/barrososemminas.org\/2021\/en\/acampada\/agenda-eng\/\">English<\/a>\n<a href=\"https:\/\/barrososemminas.org\/2021\/en\/acampada\/agenda-fr\/\">Fran\u00e7ais<\/a><\/p><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1628024105018 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628024105019  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1628024105020'  data-addon-id='1628024105020'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h1 class=\"wppb-addon-title\">Agenda<\/h1><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791648066 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648067  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626791648068'  data-addon-id='1626791648068'><div class='wppb-addon'><div class=\"wppb-animated-counter-addon\"><div class=\"wppb-animated-counter-content animated-layout-one\"><div class=\"wppb-counter-number\" data-digit=\"14\" data-duration=\"0\">0<\/div><div class=\"wppb-count-number-title\">Ao\u00fbt<\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791647955 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791647952  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947633425'  data-addon-id='1626947633425'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">8h30 - 9h15<\/span><div class=\"wppb-person-introtext\">Petit-D\u00e8j'<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791647951  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626792091599'  data-addon-id='1626792091599'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">9h30<\/span><div class=\"wppb-person-introtext\">Session de bienvenue au campement<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617586  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617587'  data-addon-id='1626947617587'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">10h<\/span><span class=\"wppb-person-designation\">Assembl\u00e9e d'introduction<\/span><div class=\"wppb-person-introtext\">Pr\u00e9sentation et organisation colective de l'espace<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627991642257  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627991642258'  data-addon-id='1627991642258'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">11h30<\/span><div class=\"wppb-person-introtext\">Atelier \u201cRitmos de Resist\u00eancia\u201d [animation musicale en manif]<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626947617604 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617603  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617594'  data-addon-id='1626947617594'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">13h<\/span><div class=\"wppb-person-introtext\">Repas\n<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791648357 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648360  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617629'  data-addon-id='1626947617629'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">14h30<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Barroso \"Patrimoine Agricole Mondial\", Quotidien et d\u00e9fis d'un mode de vie en simbiose avec la nature<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627991642285  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627991642286'  data-addon-id='1627991642286'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">17h<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Journalisme et les mouvements en d\u00e9fense du territoire et de l'environnement au Portugal<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648361  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617632'  data-addon-id='1626947617632'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">20h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648362  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617645'  data-addon-id='1626947617645'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><div class=\"wppb-person-introtext\">Moment musical et conv\u00edvial<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791647965 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791647964  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626792007653'  data-addon-id='1626792007653'><div class='wppb-addon'><div class=\"wppb-animated-counter-addon\"><div class=\"wppb-animated-counter-content animated-layout-one\"><div class=\"wppb-counter-number\" data-digit=\"15\" data-duration=\"0\">0<\/div><div class=\"wppb-count-number-title\">Ao\u00fbt<\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376204 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376205  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376206'  data-addon-id='1626953376206'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">8h30 - 9h15<\/span><div class=\"wppb-person-introtext\">Petit-D\u00e8j'<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376207  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376208'  data-addon-id='1626953376208'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">9h30<\/span><span class=\"wppb-person-designation\">Assembl\u00e9e<\/span><div class=\"wppb-person-introtext\">luttes anti-min\u00e9ration au Portugal et en Galice<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628024999619  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1627054553593 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627054553594  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627054553595'  data-addon-id='1627054553595'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">13h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626947617728 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617774  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617775'  data-addon-id='1626947617775'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">14h30<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">2050 - pour un monde sans mines<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617726  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617731'  data-addon-id='1626947617731'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">17h<\/span><span class=\"wppb-person-designation\">Asso Celtiberus<\/span><div class=\"wppb-person-introtext\">Marche par le village et ses alentours<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617727  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617766'  data-addon-id='1626947617766'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">20h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626947617767  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626947617773'  data-addon-id='1626947617773'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><span class=\"wppb-person-designation\">Projection<\/span><div class=\"wppb-person-introtext\">court-m\u00e9trage sur la manif \u00e0 la Serra da Estrela contre la mineration (2019), Tiago Cerveira <\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627991642391  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627991642392'  data-addon-id='1627991642392'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><span class=\"wppb-person-designation\">Projection<\/span><div class=\"wppb-person-introtext\">documentaire \"Bostofrio\", Paulo Carneiro + moment convivial<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791648077 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648078  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626791648079'  data-addon-id='1626791648079'><div class='wppb-addon'><div class=\"wppb-animated-counter-addon\"><div class=\"wppb-animated-counter-content animated-layout-one\"><div class=\"wppb-counter-number\" data-digit=\"16\" data-duration=\"0\">0<\/div><div class=\"wppb-count-number-title\">Ao\u00fbt<\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376280 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376281  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376282'  data-addon-id='1626953376282'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">8h30 - 9h15<\/span><div class=\"wppb-person-introtext\">Petit-D\u00e8j'<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376283  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376284'  data-addon-id='1626953376284'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">9h30<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Campagne Emploi pour le Climat<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376285  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376286'  data-addon-id='1626953376286'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">11h30<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Est ce la lutte anti-min\u00e9ration une lutte pour un changement de paradigme economique, social et politique?<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1627054553596 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627054553597  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627054553598'  data-addon-id='1627054553598'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">13h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376290 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376291  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376292'  data-addon-id='1626953376292'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">14h30<\/span><div class=\"wppb-person-introtext\">Reunion de preparation de l'action simbolique + atelier d'affiches<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376293  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376294'  data-addon-id='1626953376294'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">18h<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Transition Energetique, Mobilit\u00e9 sustentable et Justice Climatique<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376295  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376296'  data-addon-id='1626953376296'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">20h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376297  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376298'  data-addon-id='1626953376298'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><span class=\"wppb-person-designation\">Projection<\/span><div class=\"wppb-person-introtext\">documentaire \"En todas as mans\" [sur la gestion communale des terrains], Diana Toucedo + moment conv\u00edvial <\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791648093 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648094  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626791648095'  data-addon-id='1626791648095'><div class='wppb-addon'><div class=\"wppb-animated-counter-addon\"><div class=\"wppb-animated-counter-content animated-layout-one\"><div class=\"wppb-counter-number\" data-digit=\"17\" data-duration=\"0\">0<\/div><div class=\"wppb-count-number-title\">Ao\u00fbt<\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1628025000083 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628025000082  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1628025782307'  data-addon-id='1628025782307'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h2 class=\"wppb-addon-title\">Journ\u00e9e organis\u00e9e par la \u00ab Caravane zapatiste pour la vie \u00bb<\/h2><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376318 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376319  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376320'  data-addon-id='1626953376320'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">8h30 - 9h15<\/span><div class=\"wppb-person-introtext\">Petit-D\u00e8j'<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376321  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376322'  data-addon-id='1626953376322'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">9h30<\/span><div class=\"wppb-person-introtext\">D\u00e9fendre le territoire : strat\u00e9gies et tactiques de r\u00e9sistance<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1627054553599 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627054553600  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627054553601'  data-addon-id='1627054553601'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">13h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376328 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376329  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376330'  data-addon-id='1626953376330'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">14h30<\/span><div class=\"wppb-person-introtext\">Autonomie du territoire : Exp\u00e9riences d'organisation d\u00e9centralis\u00e9e<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376333  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376334'  data-addon-id='1626953376334'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">18h<\/span><div class=\"wppb-person-introtext\">Atelier d'autod\u00e9fense num\u00e9rique et l'arm\u00e9e de l'air zapatiste<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628075247023  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1628028311131'  data-addon-id='1628028311131'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">20h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628075247027  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1628028311138'  data-addon-id='1628028311138'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><div class=\"wppb-person-introtext\">Soir\u00e9e de jeux : jeu d'autonomie zapatiste<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626791648090 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626791648091  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626791648092'  data-addon-id='1626791648092'><div class='wppb-addon'><div class=\"wppb-animated-counter-addon\"><div class=\"wppb-animated-counter-content animated-layout-one\"><div class=\"wppb-counter-number\" data-digit=\"18\" data-duration=\"0\">0<\/div><div class=\"wppb-count-number-title\">Ao\u00fbt<\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376299 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376300  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376301'  data-addon-id='1626953376301'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">8h30 - 9h15<\/span><div class=\"wppb-person-introtext\">Petit-D\u00e8j'<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376302  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376303'  data-addon-id='1626953376303'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">9h30<\/span><div class=\"wppb-person-introtext\">Action simbolique<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1627054553602 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1627054553603  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1627054553604'  data-addon-id='1627054553604'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">13h<\/span><div class=\"wppb-person-introtext\">Almo\u00e7o\n<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1626953376309 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376310  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376311'  data-addon-id='1626953376311'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">14h30<\/span><span class=\"wppb-person-designation\">Discussion<\/span><div class=\"wppb-person-introtext\">Femmes et les luttes en d\u00e9fense du territoire et du mouvement<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376312  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376313'  data-addon-id='1626953376313'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">16h30<\/span><div class=\"wppb-person-introtext\">Apr\u00e8s-midi pour se d\u00e9tendre e d\u00e9ambuler<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376314  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376315'  data-addon-id='1626953376315'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">20h<\/span><div class=\"wppb-person-introtext\">Repas<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1626953376316  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1626953376317'  data-addon-id='1626953376317'><div class='wppb-addon'><div class=\"wppb-person-addon\"><div class=\"wppb-person-addon-content person-layout-one\"><div class=\"wppb-person-information\"><span class=\"wppb-person-name\">21h30<\/span><span class=\"wppb-person-designation\">Projection<\/span><div class=\"wppb-person-introtext\">Documentaire \u201cLa revolution des noix de coco\u201d, Dom Rotheroe<\/div><\/div><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1628075247034 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628075247033  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div id=\"footer\" class=\"wppb-row-parent  wppb-row-1628011258092 \"  >\n\t\t\t\t\t\n\t\t\t\t\t                        <div class=\"wppb-shape-container wppb-top-shape\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n    <path d=\"M0,6V0H1000V100Z\" transform=\"translate(0 0)\"\/>\n<\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628011258093  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-widget-1628010577180 wppb-addon-1628010577180'  data-addon-id='1628010577180'><div class='wppb-widget'><nav class=\"menu-1-container\" aria-label=\"Menu\"><ul id=\"menu-1\" class=\"menu\"><li id=\"menu-item-426\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-426\"><a href=\"https:\/\/barrososemminas.org\/2021\/acampada\/\">ACAMPADA<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-427\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-427\"><a href=\"https:\/\/barrososemminas.org\/2021\/\">Manifesto<\/a><\/li>\n\t<li id=\"menu-item-428\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-428\"><a href=\"https:\/\/barrososemminas.org\/2021\/acampada\/agenda\/\">Agenda<\/a><\/li>\n\t<li id=\"menu-item-431\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-431\"><a href=\"https:\/\/barrososemminas.org\/2021\/?page_id=41\">Sobre o Barroso<\/a><\/li>\n\t<li id=\"menu-item-430\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-430\"><a href=\"https:\/\/barrososemminas.org\/2021\/acampada\/covid-19-consenso\/\">COVID-19 \u2013 CONSENSO<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628011258095  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-widget-1628010589973 wppb-addon-1628010589973'  data-addon-id='1628010589973'><div class='wppb-widget'><nav class=\"menu-2-container\" aria-label=\"Menu\"><ul id=\"menu-2\" class=\"menu\"><li id=\"menu-item-432\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-432\"><a href=\"https:\/\/barrososemminas.org\/2021\/apoiar\/\">APOIAR<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-433\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-433\"><a href=\"https:\/\/barrososemminas.org\/2021\/apoiar\/inscreve-te\/\">Inscreve-te<\/a><\/li>\n\t<li id=\"menu-item-434\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-434\"><a href=\"https:\/\/barrososemminas.org\/2021\/apoiar\/como-chegar\/\">Como chegar<\/a><\/li>\n\t<li id=\"menu-item-436\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-436\"><a href=\"https:\/\/barrososemminas.org\/2021\/bicicletada-contra-as-minas-2021-em-defesa-do-barroso\/\">Vem de Bicicleta!<\/a><\/li>\n\t<li id=\"menu-item-435\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-435\"><a href=\"https:\/\/barrososemminas.org\/2021\/apoiar\/donativos\/\">Donativos<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628011258097  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-widget-1628010290301 wppb-addon-1628010290301'  data-addon-id='1628010290301'><div class='wppb-widget'><nav class=\"menu-3-container\" aria-label=\"Menu\"><ul id=\"menu-3\" class=\"menu\"><li id=\"menu-item-437\" class=\"menu-item menu-item-type-post_type menu-item-object-page current_page_parent menu-item-437\"><a href=\"https:\/\/barrososemminas.org\/2021\/blog\/\">NOVIDADES<\/a><\/li>\n<li id=\"menu-item-438\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-438\"><a href=\"https:\/\/barrososemminas.org\/2021\/coletivos\/\">COLETIVOS<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-439\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-439\"><a href=\"https:\/\/barrososemminas.org\/2021\/coletivos\/amigos\/\">Amigos<\/a><\/li>\n\t<li id=\"menu-item-440\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-440\"><a href=\"https:\/\/barrososemminas.org\/2021\/coletivos\/locais\/\">Do Barroso<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1628011258099  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-widget-1628010599014 wppb-addon-1628010599014'  data-addon-id='1628010599014'><div class='wppb-widget'><nav class=\"menu-4-container\" aria-label=\"Menu\"><ul id=\"menu-4\" class=\"menu\"><li id=\"menu-item-441\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-441\"><a href=\"https:\/\/barrososemminas.org\/2021\/extras-2\/\">EXTRAS<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-442\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-442\"><a href=\"https:\/\/barrososemminas.org\/2021\/extras-2\/comunicados-de-imprensa\/\">Comunicados de Imprensa<\/a><\/li>\n\t<li id=\"menu-item-443\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-443\"><a href=\"https:\/\/barrososemminas.org\/2021\/extras-2\/ilustracao\/\">Material para divulga\u00e7\u00e3o<\/a><\/li>\n\t<li id=\"menu-item-482\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-482\"><a href=\"https:\/\/barrososemminas.org\/2021\/mencoes-na-imprensa\/\">Men\u00e7\u00f5es na Imprensa<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-444\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-444\"><a href=\"https:\/\/barrososemminas.org\/2021\/acampada\/contacta-nos\/\">CONTACTA-NOS<\/a><\/li>\n<\/ul><\/nav><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Portugu\u00eas\/Galego English Fran\u00e7ais Agenda 0 Ao\u00fbt 8h30 &#8211; 9h15 Petit-D\u00e8j&#8217; 9h30 Session de bienvenue au campement 10hAssembl\u00e9e d&#8217;introduction Pr\u00e9sentation et organisation colective de l&#8217;espace 11h30 Atelier \u201cRitmos de Resist\u00eancia\u201d [animation musicale en manif] 13h Repas 14h30Discussion Barroso &#8220;Patrimoine Agricole Mondial&#8221;, Quotidien et d\u00e9fis d&#8217;un mode de vie en simbiose avec la nature 17hDiscussion Journalisme et &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/barrososemminas.org\/2021\/fr\/acampada\/agenda-fr\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Agenda Fran\u00e7ais&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":25,"menu_order":26,"comment_status":"closed","ping_status":"closed","template":"wppb_theme_template","meta":[],"_links":{"self":[{"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/pages\/463"}],"collection":[{"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":2,"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/pages\/463\/revisions"}],"predecessor-version":[{"id":468,"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/pages\/463\/revisions\/468"}],"up":[{"embeddable":true,"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/pages\/25"}],"wp:attachment":[{"href":"https:\/\/barrososemminas.org\/2021\/wp-json\/wp\/v2\/media?parent=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}